{"id":6986,"date":"2019-06-21T09:39:20","date_gmt":"2019-06-21T13:39:20","guid":{"rendered":"https:\/\/finvest.ca\/?p=6986"},"modified":"2019-06-21T09:41:09","modified_gmt":"2019-06-21T13:41:09","slug":"6986","status":"publish","type":"post","link":"https:\/\/finvest.ca\/en\/6986\/","title":{"rendered":"Quel niveau de risque pouvez-vous tol\u00e9rer?"},"content":{"rendered":"<table class=\"wp-block-table alignleft\"><tbody><tr><td>Le 17 juin 2019<br>&nbsp;<strong>Quel niveau de risque pouvez-vous tol\u00e9rer?<\/strong><br><br>&nbsp;Qui d\u2019entre nous n\u2019aimerait pas des rendements de 15% par ann\u00e9e sur ses placements? On pourrait m\u00eame entrevoir prendre notre retraite cinq ans plus t\u00f4t. Serions-nous pr\u00eats \u00e0 prendre le risque d\u2019avoir \u00e0 la retarder cinq ans si l\u2019inverse se produisait.<br><br>Plus le potentiel de gain d\u2019un placement est \u00e9lev\u00e9, plus le risque de voir son capital diminu\u00e9 l\u2019est aussi. Gains et risques vont toujours de pair !<br><br><strong>Volatilit\u00e9 du portefeuille<\/strong><br>Une des meilleures mesures du risque d\u2019un portefeuille est sa volatilit\u00e9. La volatilit\u00e9 mesure la variabilit\u00e9 de la valeur du portefeuille. Un portefeuille qui, historiquement, a vari\u00e9 de +ou- 25% est plus risqu\u00e9 que celui qui n\u2019a vari\u00e9 que de 5%. \u00c9videmment, l\u2019esp\u00e9rance de gain est plus faible avec le deuxi\u00e8me.<br><br><strong>Sur les march\u00e9s, le pass\u00e9 n\u2019est pas n\u00e9cessairement garant du futur.<\/strong><br><br><strong>Fronti\u00e8re efficiente<\/strong><br>Un portefeuille est efficient si l\u2019une ou l\u2019autre des conditions suivantes est rencontr\u00e9e&nbsp;:Pour un niveau donn\u00e9 de rendement esp\u00e9r\u00e9, il n\u2019existe aucun autre portefeuille comportant moins de risque.Pour un niveau de risque donn\u00e9, il n\u2019existe aucun autre portefeuille ayant une esp\u00e9rance de rendement plus \u00e9lev\u00e9.M\u00eame si le risque est proportionnel au gain escompt\u00e9, on peut toujours trouver un portefeuille ou le couple esp\u00e9rance de gain vs risque sera le plus avantageux pour l\u2019investisseur.<br><br>Un professionnel de la finance commencera par mesurer votre niveau de risque acceptable. Celui qui vous permet de bien dormir la nuit. De l\u00e0, il construira un ou des portefeuilles correspondant \u00e0 votre profil de risque et situ\u00e9 sur la fronti\u00e8re efficiente.<br><br>En tant que professionnel ind\u00e9pendant, nous avons les outils et les connaissances pour vous conseiller en mati\u00e8re de placements. Nous n\u2019avons aucune contrainte ou quota \u00e0 respecter dans le choix de vos placements.<br><br>Finalement, en tant que votre conseiller, nous devons tout mettre en \u0153uvre pour am\u00e9liorer l\u2019efficience de votre portefeuille.<br>&nbsp;<strong>Mauro DiCesare, B.Comm, Pl.Fin<\/strong><br>Planificateur Financier\/Financial Planner&nbsp;<br>Financial Security Advisor\/Conseiller en S\u00e9curit\u00e9 Financi\u00e8re avec Groupe Financier Finvest Inc.<br>Mutual Fund Representative\/Repr\u00e9sentant en \u00e9pargne collective avec Investia Services Financiers&nbsp;Inc.<br>514-376-7771<\/td><\/tr><\/tbody><\/table>\n\n\n\n<table class=\"wp-block-table\"><tbody><tr><td>\n\n<\/td><\/tr><\/tbody><\/table>","protected":false},"excerpt":{"rendered":"<p>Le 17 juin 2019&nbsp;Quel niveau de risque pouvez-vous tol\u00e9rer? &nbsp;Qui d\u2019entre nous n\u2019aimerait pas des rendements de 15% par ann\u00e9e sur ses placements? On pourrait m\u00eame entrevoir prendre notre retraite cinq ans plus t\u00f4t. Serions-nous pr\u00eats \u00e0 prendre le risque d\u2019avoir \u00e0 la retarder cinq ans si l\u2019inverse se produisait. Plus le potentiel de gain [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6986","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quel niveau de risque pouvez-vous tol\u00e9rer? - Finvest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/finvest.ca\/en\/6986\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quel niveau de risque pouvez-vous tol\u00e9rer? - Finvest\" \/>\n<meta property=\"og:description\" content=\"Le 17 juin 2019&nbsp;Quel niveau de risque pouvez-vous tol\u00e9rer? &nbsp;Qui d\u2019entre nous n\u2019aimerait pas des rendements de 15% par ann\u00e9e sur ses placements? On pourrait m\u00eame entrevoir prendre notre retraite cinq ans plus t\u00f4t. Serions-nous pr\u00eats \u00e0 prendre le risque d\u2019avoir \u00e0 la retarder cinq ans si l\u2019inverse se produisait. Plus le potentiel de gain [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/finvest.ca\/en\/6986\/\" \/>\n<meta property=\"og:site_name\" content=\"Finvest\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-21T13:39:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-21T13:41:09+00:00\" \/>\n<meta name=\"author\" content=\"Finvest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Finvest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/finvest.ca\\\/6986\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/finvest.ca\\\/6986\\\/\"},\"author\":{\"name\":\"Finvest\",\"@id\":\"https:\\\/\\\/finvest.ca\\\/#\\\/schema\\\/person\\\/d9697696301ac54510f0da1d14005ec8\"},\"headline\":\"Quel niveau de risque pouvez-vous tol\u00e9rer?\",\"datePublished\":\"2019-06-21T13:39:20+00:00\",\"dateModified\":\"2019-06-21T13:41:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/finvest.ca\\\/6986\\\/\"},\"wordCount\":392,\"commentCount\":0,\"articleSection\":[\"Non class\u00e9\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/finvest.ca\\\/6986\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/finvest.ca\\\/6986\\\/\",\"url\":\"https:\\\/\\\/finvest.ca\\\/6986\\\/\",\"name\":\"Quel niveau de risque pouvez-vous tol\u00e9rer? - Finvest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/finvest.ca\\\/#website\"},\"datePublished\":\"2019-06-21T13:39:20+00:00\",\"dateModified\":\"2019-06-21T13:41:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/finvest.ca\\\/#\\\/schema\\\/person\\\/d9697696301ac54510f0da1d14005ec8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/finvest.ca\\\/6986\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/finvest.ca\\\/6986\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/finvest.ca\\\/6986\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/finvest.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quel niveau de risque pouvez-vous tol\u00e9rer?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/finvest.ca\\\/#website\",\"url\":\"https:\\\/\\\/finvest.ca\\\/\",\"name\":\"Finvest\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/finvest.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/finvest.ca\\\/#\\\/schema\\\/person\\\/d9697696301ac54510f0da1d14005ec8\",\"name\":\"Finvest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cf66dc67542179696c84ad56012869a8b41e0745625a8a58b38d05997835365?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cf66dc67542179696c84ad56012869a8b41e0745625a8a58b38d05997835365?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cf66dc67542179696c84ad56012869a8b41e0745625a8a58b38d05997835365?s=96&d=mm&r=g\",\"caption\":\"Finvest\"},\"sameAs\":[\"http:\\\/\\\/www.hostingbros.ca\"],\"url\":\"https:\\\/\\\/finvest.ca\\\/en\\\/author\\\/finvest\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quel niveau de risque pouvez-vous tol\u00e9rer? - Finvest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/finvest.ca\/en\/6986\/","og_locale":"en_US","og_type":"article","og_title":"Quel niveau de risque pouvez-vous tol\u00e9rer? - Finvest","og_description":"Le 17 juin 2019&nbsp;Quel niveau de risque pouvez-vous tol\u00e9rer? &nbsp;Qui d\u2019entre nous n\u2019aimerait pas des rendements de 15% par ann\u00e9e sur ses placements? On pourrait m\u00eame entrevoir prendre notre retraite cinq ans plus t\u00f4t. Serions-nous pr\u00eats \u00e0 prendre le risque d\u2019avoir \u00e0 la retarder cinq ans si l\u2019inverse se produisait. Plus le potentiel de gain [&hellip;]","og_url":"https:\/\/finvest.ca\/en\/6986\/","og_site_name":"Finvest","article_published_time":"2019-06-21T13:39:20+00:00","article_modified_time":"2019-06-21T13:41:09+00:00","author":"Finvest","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Finvest","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/finvest.ca\/6986\/#article","isPartOf":{"@id":"https:\/\/finvest.ca\/6986\/"},"author":{"name":"Finvest","@id":"https:\/\/finvest.ca\/#\/schema\/person\/d9697696301ac54510f0da1d14005ec8"},"headline":"Quel niveau de risque pouvez-vous tol\u00e9rer?","datePublished":"2019-06-21T13:39:20+00:00","dateModified":"2019-06-21T13:41:09+00:00","mainEntityOfPage":{"@id":"https:\/\/finvest.ca\/6986\/"},"wordCount":392,"commentCount":0,"articleSection":["Non class\u00e9"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/finvest.ca\/6986\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/finvest.ca\/6986\/","url":"https:\/\/finvest.ca\/6986\/","name":"Quel niveau de risque pouvez-vous tol\u00e9rer? - Finvest","isPartOf":{"@id":"https:\/\/finvest.ca\/#website"},"datePublished":"2019-06-21T13:39:20+00:00","dateModified":"2019-06-21T13:41:09+00:00","author":{"@id":"https:\/\/finvest.ca\/#\/schema\/person\/d9697696301ac54510f0da1d14005ec8"},"breadcrumb":{"@id":"https:\/\/finvest.ca\/6986\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/finvest.ca\/6986\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/finvest.ca\/6986\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/finvest.ca\/"},{"@type":"ListItem","position":2,"name":"Quel niveau de risque pouvez-vous tol\u00e9rer?"}]},{"@type":"WebSite","@id":"https:\/\/finvest.ca\/#website","url":"https:\/\/finvest.ca\/","name":"Finvest","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/finvest.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/finvest.ca\/#\/schema\/person\/d9697696301ac54510f0da1d14005ec8","name":"Finvest","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2cf66dc67542179696c84ad56012869a8b41e0745625a8a58b38d05997835365?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2cf66dc67542179696c84ad56012869a8b41e0745625a8a58b38d05997835365?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cf66dc67542179696c84ad56012869a8b41e0745625a8a58b38d05997835365?s=96&d=mm&r=g","caption":"Finvest"},"sameAs":["http:\/\/www.hostingbros.ca"],"url":"https:\/\/finvest.ca\/en\/author\/finvest\/"}]}},"_links":{"self":[{"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/posts\/6986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/comments?post=6986"}],"version-history":[{"count":4,"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/posts\/6986\/revisions"}],"predecessor-version":[{"id":6990,"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/posts\/6986\/revisions\/6990"}],"wp:attachment":[{"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/media?parent=6986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/categories?post=6986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/tags?post=6986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}