{"id":7038,"date":"2020-09-27T11:24:51","date_gmt":"2020-09-27T15:24:51","guid":{"rendered":"https:\/\/finvest.ca\/?p=7038"},"modified":"2020-09-27T11:24:52","modified_gmt":"2020-09-27T15:24:52","slug":"la-covid-19-et-votre-retraite","status":"publish","type":"post","link":"https:\/\/finvest.ca\/en\/la-covid-19-et-votre-retraite\/","title":{"rendered":"La Covid-19 et votre retraite"},"content":{"rendered":"<p>Le 23 Septembre 2020,\u00a0<\/p>\n\n\n\n<p>                            <strong>\u00a0\u00a0 \u00a0 \u00a0 \u00a0 La COVID-19 et votre retraite<\/strong><\/p>\n\n\n\n<p><br>\u00a0Parmi les ravages effectu\u00e9s par la Covid-19 au-del\u00e0 de l\u2019aspect pand\u00e9mie, nul ne peut passer sous silence ceux faits \u00e0 votre planification de retraite. Vous avez d\u00fb utiliser vos REER pour rencontrer les imp\u00e9ratifs de votre budget, vous avez perdu votre emploi et arr\u00eat\u00e9 de contribuer, la valeur de votre REER a diminu\u00e9 sensiblement ? Comment allez-vous retomber sur vos pattes en ce qui concerne votre strat\u00e9gie de retraite\u2009?<\/p>\n\n\n\n<p><strong>Strat\u00e9gie de retraite<\/strong><br>Rappelons-nous qu\u2019une strat\u00e9gie de retraite est une toile de fond, une ligne directrice et non un plan coul\u00e9 dans le b\u00e9ton. R\u00e8gle g\u00e9n\u00e9rale, nous pouvons ensemble assez facilement ajuster cette strat\u00e9gie. Si vous n\u2019aviez pas de strat\u00e9gie, il serait \u00e9ventuellement int\u00e9ressant d\u2019en \u00e9tablir une.<\/p>\n\n\n\n<p><strong>Esp\u00e9rance vie en bonne sant\u00e9<\/strong><br>Voici une nouvelle notion \u00e0 introduire dans notre planification de retraite. Quel est le nombre d\u2019ann\u00e9es en bonne sant\u00e9 esp\u00e9rez-vous avoir \u00e0 partir du moment o\u00f9 vous prendrez votre retraite?<\/p>\n\n\n\n<p>Depuis 1994, Statistique Canada publie aux 4 ans une \u00e9tude comparative entre l\u2019esp\u00e9rance de vie et l\u2019esp\u00e9rance de vie ajust\u00e9e sur la sant\u00e9.<br>Voici les donn\u00e9es de 2015 publi\u00e9es en 2018. Pour un homme prenant sa retraite \u00e0 65 ans&nbsp;: son esp\u00e9rance de vie est de 19,2 et son esp\u00e9rance de vie en sant\u00e9 et 14,4. Pour une femme c\u2019est 22,0 et 15,3.<\/p>\n\n\n\n<p><strong>Ce concept pourrait influencer votre strat\u00e9gie de retraite. Parlons-en ensemble.<\/strong><\/p>\n\n\n\n<p><strong>Ajuster sa strat\u00e9gie de retraite.<\/strong><br>Plus on est loin de la retraite, plus il est facile d\u2019ajuster sa strat\u00e9gie. Voici quelques \u00e9l\u00e9ments \u00e0 consid\u00e9rer dans une refonte de votre strat\u00e9gie.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Votre philosophie de retraite. La Covid-19 vous a-t-elle fait envisager votre retraite de fa\u00e7on diff\u00e9rente?<\/li><li>Vos besoins de revenus \u00e0 la retraite.<\/li><li>L\u2019\u00e2ge de prise de votre retraite.<\/li><li>Votre capacit\u00e9 d\u2019\u00e9conomiser.<\/li><li>La diminution de votre capital retraite suite \u00e0 la Covid-19.<\/li><li>Votre esp\u00e9rance de vie en sant\u00e9.<\/li><li>\u2026\u2026..<\/li><\/ul>\n\n\n\n<p><strong>On doit r\u00e9viser sa strat\u00e9gie p\u00e9riodiquement. J&rsquo;encourage chacun de vous \u00e0 prendre rendez-vous avec moi pour r\u00e9viser et ajuster, au besoin, votre plan de retraite.<\/strong><br><br>&nbsp;&nbsp;Sinc\u00e8rement<br><strong>Mauro DiCesare, B.Comm, Pl.Fin<\/strong><br>Planificateur Financier\/Financial Planner&nbsp;<br>Financial Security Advisor\/Conseiller en S\u00e9curit\u00e9 Financi\u00e8re avec Groupe Financier Finvest Inc.<br>Mutual Fund Representative\/Repr\u00e9sentant en \u00e9pargne collective avec Investia Services Financiers&nbsp;Inc.<br>514-376-7771<\/p>","protected":false},"excerpt":{"rendered":"<p>Le 23 Septembre 2020,\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 La COVID-19 et votre retraite \u00a0Parmi les ravages effectu\u00e9s par la Covid-19 au-del\u00e0 de l\u2019aspect pand\u00e9mie, nul ne peut passer sous silence ceux faits \u00e0 votre planification de retraite. Vous avez d\u00fb utiliser vos REER pour rencontrer les imp\u00e9ratifs de votre budget, vous avez perdu votre emploi [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7038","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Covid-19 et votre retraite - Finvest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/finvest.ca\/en\/la-covid-19-et-votre-retraite\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Covid-19 et votre retraite - Finvest\" \/>\n<meta property=\"og:description\" content=\"Le 23 Septembre 2020,\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 La COVID-19 et votre retraite \u00a0Parmi les ravages effectu\u00e9s par la Covid-19 au-del\u00e0 de l\u2019aspect pand\u00e9mie, nul ne peut passer sous silence ceux faits \u00e0 votre planification de retraite. Vous avez d\u00fb utiliser vos REER pour rencontrer les imp\u00e9ratifs de votre budget, vous avez perdu votre emploi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/finvest.ca\/en\/la-covid-19-et-votre-retraite\/\" \/>\n<meta property=\"og:site_name\" content=\"Finvest\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-27T15:24:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-27T15:24:52+00:00\" \/>\n<meta name=\"author\" content=\"Finvest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Finvest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/finvest.ca\\\/la-covid-19-et-votre-retraite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/finvest.ca\\\/la-covid-19-et-votre-retraite\\\/\"},\"author\":{\"name\":\"Finvest\",\"@id\":\"https:\\\/\\\/finvest.ca\\\/#\\\/schema\\\/person\\\/d9697696301ac54510f0da1d14005ec8\"},\"headline\":\"La Covid-19 et votre retraite\",\"datePublished\":\"2020-09-27T15:24:51+00:00\",\"dateModified\":\"2020-09-27T15:24:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/finvest.ca\\\/la-covid-19-et-votre-retraite\\\/\"},\"wordCount\":415,\"commentCount\":0,\"articleSection\":[\"Non class\u00e9\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/finvest.ca\\\/la-covid-19-et-votre-retraite\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/finvest.ca\\\/la-covid-19-et-votre-retraite\\\/\",\"url\":\"https:\\\/\\\/finvest.ca\\\/la-covid-19-et-votre-retraite\\\/\",\"name\":\"La Covid-19 et votre retraite - Finvest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/finvest.ca\\\/#website\"},\"datePublished\":\"2020-09-27T15:24:51+00:00\",\"dateModified\":\"2020-09-27T15:24:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/finvest.ca\\\/#\\\/schema\\\/person\\\/d9697696301ac54510f0da1d14005ec8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/finvest.ca\\\/la-covid-19-et-votre-retraite\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/finvest.ca\\\/la-covid-19-et-votre-retraite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/finvest.ca\\\/la-covid-19-et-votre-retraite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/finvest.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Covid-19 et votre retraite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/finvest.ca\\\/#website\",\"url\":\"https:\\\/\\\/finvest.ca\\\/\",\"name\":\"Finvest\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/finvest.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/finvest.ca\\\/#\\\/schema\\\/person\\\/d9697696301ac54510f0da1d14005ec8\",\"name\":\"Finvest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cf66dc67542179696c84ad56012869a8b41e0745625a8a58b38d05997835365?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cf66dc67542179696c84ad56012869a8b41e0745625a8a58b38d05997835365?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cf66dc67542179696c84ad56012869a8b41e0745625a8a58b38d05997835365?s=96&d=mm&r=g\",\"caption\":\"Finvest\"},\"sameAs\":[\"http:\\\/\\\/www.hostingbros.ca\"],\"url\":\"https:\\\/\\\/finvest.ca\\\/en\\\/author\\\/finvest\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Covid-19 et votre retraite - Finvest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/finvest.ca\/en\/la-covid-19-et-votre-retraite\/","og_locale":"en_US","og_type":"article","og_title":"La Covid-19 et votre retraite - Finvest","og_description":"Le 23 Septembre 2020,\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 La COVID-19 et votre retraite \u00a0Parmi les ravages effectu\u00e9s par la Covid-19 au-del\u00e0 de l\u2019aspect pand\u00e9mie, nul ne peut passer sous silence ceux faits \u00e0 votre planification de retraite. Vous avez d\u00fb utiliser vos REER pour rencontrer les imp\u00e9ratifs de votre budget, vous avez perdu votre emploi [&hellip;]","og_url":"https:\/\/finvest.ca\/en\/la-covid-19-et-votre-retraite\/","og_site_name":"Finvest","article_published_time":"2020-09-27T15:24:51+00:00","article_modified_time":"2020-09-27T15:24:52+00:00","author":"Finvest","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Finvest","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/finvest.ca\/la-covid-19-et-votre-retraite\/#article","isPartOf":{"@id":"https:\/\/finvest.ca\/la-covid-19-et-votre-retraite\/"},"author":{"name":"Finvest","@id":"https:\/\/finvest.ca\/#\/schema\/person\/d9697696301ac54510f0da1d14005ec8"},"headline":"La Covid-19 et votre retraite","datePublished":"2020-09-27T15:24:51+00:00","dateModified":"2020-09-27T15:24:52+00:00","mainEntityOfPage":{"@id":"https:\/\/finvest.ca\/la-covid-19-et-votre-retraite\/"},"wordCount":415,"commentCount":0,"articleSection":["Non class\u00e9"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/finvest.ca\/la-covid-19-et-votre-retraite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/finvest.ca\/la-covid-19-et-votre-retraite\/","url":"https:\/\/finvest.ca\/la-covid-19-et-votre-retraite\/","name":"La Covid-19 et votre retraite - Finvest","isPartOf":{"@id":"https:\/\/finvest.ca\/#website"},"datePublished":"2020-09-27T15:24:51+00:00","dateModified":"2020-09-27T15:24:52+00:00","author":{"@id":"https:\/\/finvest.ca\/#\/schema\/person\/d9697696301ac54510f0da1d14005ec8"},"breadcrumb":{"@id":"https:\/\/finvest.ca\/la-covid-19-et-votre-retraite\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/finvest.ca\/la-covid-19-et-votre-retraite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/finvest.ca\/la-covid-19-et-votre-retraite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/finvest.ca\/"},{"@type":"ListItem","position":2,"name":"La Covid-19 et votre retraite"}]},{"@type":"WebSite","@id":"https:\/\/finvest.ca\/#website","url":"https:\/\/finvest.ca\/","name":"Finvest","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/finvest.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/finvest.ca\/#\/schema\/person\/d9697696301ac54510f0da1d14005ec8","name":"Finvest","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2cf66dc67542179696c84ad56012869a8b41e0745625a8a58b38d05997835365?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2cf66dc67542179696c84ad56012869a8b41e0745625a8a58b38d05997835365?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cf66dc67542179696c84ad56012869a8b41e0745625a8a58b38d05997835365?s=96&d=mm&r=g","caption":"Finvest"},"sameAs":["http:\/\/www.hostingbros.ca"],"url":"https:\/\/finvest.ca\/en\/author\/finvest\/"}]}},"_links":{"self":[{"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/posts\/7038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/comments?post=7038"}],"version-history":[{"count":1,"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/posts\/7038\/revisions"}],"predecessor-version":[{"id":7039,"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/posts\/7038\/revisions\/7039"}],"wp:attachment":[{"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/media?parent=7038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/categories?post=7038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/finvest.ca\/en\/wp-json\/wp\/v2\/tags?post=7038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}